{"id":108,"count":1,"description":"","link":"https:\/\/gometa.co.za\/blog\/tag\/tax-certificate-via-email\/","name":"tax certificate via email","slug":"tax-certificate-via-email","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>tax certificate via email Archives - Gometa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gometa.co.za\/blog\/tag\/tax-certificate-via-email\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"tax certificate via email Archives - Gometa\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gometa.co.za\/blog\/tag\/tax-certificate-via-email\/\" \/>\n<meta property=\"og:site_name\" content=\"Gometa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/gometa.co.za\\\/blog\\\/tag\\\/tax-certificate-via-email\\\/\",\"url\":\"https:\\\/\\\/gometa.co.za\\\/blog\\\/tag\\\/tax-certificate-via-email\\\/\",\"name\":\"tax certificate via email Archives - Gometa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gometa.co.za\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gometa.co.za\\\/blog\\\/tag\\\/tax-certificate-via-email\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gometa.co.za\\\/blog\\\/tag\\\/tax-certificate-via-email\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/gometa.co.za\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"tax certificate via email\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gometa.co.za\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/gometa.co.za\\\/blog\\\/\",\"name\":\"Gometa\",\"description\":\"Smart Search for Everyone\",\"publisher\":{\"@id\":\"https:\\\/\\\/gometa.co.za\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gometa.co.za\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gometa.co.za\\\/blog\\\/#organization\",\"name\":\"Gometa\",\"url\":\"https:\\\/\\\/gometa.co.za\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/gometa.co.za\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gometa.co.za\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/cropped-gometa.png\",\"contentUrl\":\"https:\\\/\\\/gometa.co.za\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/cropped-gometa.png\",\"width\":112,\"height\":28,\"caption\":\"Gometa\"},\"image\":{\"@id\":\"https:\\\/\\\/gometa.co.za\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/bursary24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"tax certificate via email Archives - Gometa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gometa.co.za\/blog\/tag\/tax-certificate-via-email\/","og_locale":"en_US","og_type":"article","og_title":"tax certificate via email Archives - Gometa","og_url":"https:\/\/gometa.co.za\/blog\/tag\/tax-certificate-via-email\/","og_site_name":"Gometa","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/gometa.co.za\/blog\/tag\/tax-certificate-via-email\/","url":"https:\/\/gometa.co.za\/blog\/tag\/tax-certificate-via-email\/","name":"tax certificate via email Archives - Gometa","isPartOf":{"@id":"https:\/\/gometa.co.za\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/gometa.co.za\/blog\/tag\/tax-certificate-via-email\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/gometa.co.za\/blog\/tag\/tax-certificate-via-email\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/gometa.co.za\/blog\/"},{"@type":"ListItem","position":2,"name":"tax certificate via email"}]},{"@type":"WebSite","@id":"https:\/\/gometa.co.za\/blog\/#website","url":"https:\/\/gometa.co.za\/blog\/","name":"Gometa","description":"Smart Search for Everyone","publisher":{"@id":"https:\/\/gometa.co.za\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gometa.co.za\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/gometa.co.za\/blog\/#organization","name":"Gometa","url":"https:\/\/gometa.co.za\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/gometa.co.za\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/gometa.co.za\/blog\/wp-content\/uploads\/2025\/07\/cropped-gometa.png","contentUrl":"https:\/\/gometa.co.za\/blog\/wp-content\/uploads\/2025\/07\/cropped-gometa.png","width":112,"height":28,"caption":"Gometa"},"image":{"@id":"https:\/\/gometa.co.za\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/bursary24\/"]}]}},"_links":{"self":[{"href":"https:\/\/gometa.co.za\/blog\/wp-json\/wp\/v2\/tags\/108","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gometa.co.za\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/gometa.co.za\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/gometa.co.za\/blog\/wp-json\/wp\/v2\/posts?tags=108"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}